{"id":23492,"date":"2024-10-04T19:17:06","date_gmt":"2024-10-04T19:17:06","guid":{"rendered":"https:\/\/thetenerifechannel.com\/product\/opera-33-privat-charter\/"},"modified":"2026-07-14T16:38:33","modified_gmt":"2026-07-14T15:38:33","slug":"opera-33-privat-charter","status":"publish","type":"product","link":"https:\/\/thetenerifechannel.com\/de\/excursions\/opera-33-privat-charter\/","title":{"rendered":"Opera 33 Privat-Charter"},"content":{"rendered":"<section class=\"l-section wpb_row height_huge\"><div class=\"l-section-h i-cf\"><div class=\"g-cols vc_row via_grid cols_1 laptops-cols_inherit tablets-cols_inherit mobiles-cols_1 valign_top type_default stacking_default\"><div class=\"wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><p><span>Erleben Sie den Luxus eines  <\/span><span>Privatcharter auf Teneriffa! Genie\u00dfen Sie einen exklusiven, dreist\u00fcndigen Bootsausflug entlang der wundersch\u00f6nen K\u00fcste, inklusive einer erfrischenden Badepause und einem k\u00f6stlichen Mittagessen an Bord. Perfekt f\u00fcr alle, die sich entspannen, abschalten und die Gew\u00e4sser Teneriffas stilvoll erkunden m\u00f6chten.<br \/>\nMaximale Kapazit\u00e4t: 11 Personen  <\/span><\/p>\n<p><strong>INKLUSIVE:<\/strong><\/p>\n<ul>\n<li>3 Stunden Tour<\/li>\n<li>Schwimmstopp<\/li>\n<li>Mittagessen und Getr\u00e4nke<\/li>\n<\/ul>\n<p>*Bitte beachten Sie, dass es zwar m\u00f6glich ist, dass Sie w\u00e4hrend der Fahrt Wale sehen, der Schwerpunkt dieser Bootstour aber nicht auf der Walbeobachtung liegt. Das Boot ist f\u00fcr ein entspanntes und landschaftlich reizvolles Erlebnis entlang der wundersch\u00f6nen K\u00fcste Teneriffas konzipiert. Ein Badestopp und ein Mittagessen sind inbegriffen und bieten Ihnen die perfekte M\u00f6glichkeit, einen luxuri\u00f6sen Tag auf dem Meer zu genie\u00dfen.<\/p>\n<\/div><\/div><\/div><\/div><\/div><\/div><\/section>\n","protected":false},"excerpt":{"rendered":"<p><span>G\u00f6nnen Sie sich eine 3-st\u00fcndige private Bootstour mit einem erfrischenden Badestopp und einem k\u00f6stlichen Mittagessen an Bord.<\/span><\/p>\n<p><strong>*Bitte kontaktieren Sie uns immer, bevor Sie diesen privaten Charter buchen.<\/strong><\/p>\n","protected":false},"featured_media":21931,"template":"","meta":{"_acf_changed":false,"_joinchat":[]},"product_brand":[],"product_cat":[230],"product_tag":[],"class_list":["post-23492","product","type-product","status-publish","has-post-thumbnail","product_cat-privat-charter-teneriffa","first","instock","virtual","sold-individually","purchasable","product-type-booking"],"acf":[],"_links":{"self":[{"href":"https:\/\/thetenerifechannel.com\/de\/wp-json\/wp\/v2\/product\/23492","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/thetenerifechannel.com\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/thetenerifechannel.com\/de\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/thetenerifechannel.com\/de\/wp-json\/wp\/v2\/media\/21931"}],"wp:attachment":[{"href":"https:\/\/thetenerifechannel.com\/de\/wp-json\/wp\/v2\/media?parent=23492"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/thetenerifechannel.com\/de\/wp-json\/wp\/v2\/product_brand?post=23492"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/thetenerifechannel.com\/de\/wp-json\/wp\/v2\/product_cat?post=23492"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/thetenerifechannel.com\/de\/wp-json\/wp\/v2\/product_tag?post=23492"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}